{"id":238,"date":"2020-04-14T19:11:05","date_gmt":"2020-04-14T19:11:05","guid":{"rendered":"https:\/\/wwwdev.smca.ucf.edu\/research\/person\/charlie-hughes\/"},"modified":"2025-05-21T14:35:19","modified_gmt":"2025-05-21T14:35:19","slug":"charlie-hughes","status":"publish","type":"person","link":"https:\/\/www.ucf.edu\/research\/person\/charlie-hughes\/","title":{"rendered":"<a href=\"https:\/\/www.cecs.ucf.edu\/faculty\/charles-hughes\/\" target=\"_blank\" rel=\"noopener noreferrer\">Charlie Hughes, Ph.D.<\/a>"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":4753,"template":"","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"tags":[],"class_list":["post-238","person","type-person","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Charlie Hughes, Ph.D. | Research<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ucf.edu\/research\/person\/charlie-hughes\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Charlie Hughes, Ph.D. | Research\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ucf.edu\/research\/person\/charlie-hughes\/\" \/>\n<meta property=\"og:site_name\" content=\"Research\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-21T14:35:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ucf.edu\/research\/wp-content\/uploads\/sites\/2\/2020\/04\/Charlie-Hughes450EDIT-scaled-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ucf.edu\\\/research\\\/person\\\/charlie-hughes\\\/\",\"url\":\"https:\\\/\\\/www.ucf.edu\\\/research\\\/person\\\/charlie-hughes\\\/\",\"name\":\"Charlie Hughes, Ph.D. | Research\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ucf.edu\\\/research\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ucf.edu\\\/research\\\/person\\\/charlie-hughes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ucf.edu\\\/research\\\/person\\\/charlie-hughes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ucf.edu\\\/research\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/04\\\/Charlie-Hughes450EDIT-scaled-1.jpg\",\"datePublished\":\"2020-04-14T19:11:05+00:00\",\"dateModified\":\"2025-05-21T14:35:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ucf.edu\\\/research\\\/person\\\/charlie-hughes\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ucf.edu\\\/research\\\/person\\\/charlie-hughes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.ucf.edu\\\/research\\\/person\\\/charlie-hughes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ucf.edu\\\/research\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/04\\\/Charlie-Hughes450EDIT-scaled-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ucf.edu\\\/research\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/04\\\/Charlie-Hughes450EDIT-scaled-1.jpg\",\"width\":2560,\"height\":2560,\"caption\":\"Professional Headshot\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ucf.edu\\\/research\\\/person\\\/charlie-hughes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ucf.edu\\\/research\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Charlie Hughes, Ph.D.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ucf.edu\\\/research\\\/#website\",\"url\":\"https:\\\/\\\/www.ucf.edu\\\/research\\\/\",\"name\":\"Research\",\"description\":\"Just another EDURES CMS QA Admin site Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ucf.edu\\\/research\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Charlie Hughes, Ph.D. | Research","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ucf.edu\/research\/person\/charlie-hughes\/","og_locale":"en_US","og_type":"article","og_title":"Charlie Hughes, Ph.D. | Research","og_url":"https:\/\/www.ucf.edu\/research\/person\/charlie-hughes\/","og_site_name":"Research","article_modified_time":"2025-05-21T14:35:19+00:00","og_image":[{"width":2560,"height":2560,"url":"https:\/\/www.ucf.edu\/research\/wp-content\/uploads\/sites\/2\/2020\/04\/Charlie-Hughes450EDIT-scaled-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ucf.edu\/research\/person\/charlie-hughes\/","url":"https:\/\/www.ucf.edu\/research\/person\/charlie-hughes\/","name":"Charlie Hughes, Ph.D. | Research","isPartOf":{"@id":"https:\/\/www.ucf.edu\/research\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ucf.edu\/research\/person\/charlie-hughes\/#primaryimage"},"image":{"@id":"https:\/\/www.ucf.edu\/research\/person\/charlie-hughes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ucf.edu\/research\/wp-content\/uploads\/sites\/2\/2020\/04\/Charlie-Hughes450EDIT-scaled-1.jpg","datePublished":"2020-04-14T19:11:05+00:00","dateModified":"2025-05-21T14:35:19+00:00","breadcrumb":{"@id":"https:\/\/www.ucf.edu\/research\/person\/charlie-hughes\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ucf.edu\/research\/person\/charlie-hughes\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.ucf.edu\/research\/person\/charlie-hughes\/#primaryimage","url":"https:\/\/www.ucf.edu\/research\/wp-content\/uploads\/sites\/2\/2020\/04\/Charlie-Hughes450EDIT-scaled-1.jpg","contentUrl":"https:\/\/www.ucf.edu\/research\/wp-content\/uploads\/sites\/2\/2020\/04\/Charlie-Hughes450EDIT-scaled-1.jpg","width":2560,"height":2560,"caption":"Professional Headshot"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ucf.edu\/research\/person\/charlie-hughes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ucf.edu\/research\/"},{"@type":"ListItem","position":2,"name":"Charlie Hughes, Ph.D."}]},{"@type":"WebSite","@id":"https:\/\/www.ucf.edu\/research\/#website","url":"https:\/\/www.ucf.edu\/research\/","name":"Research","description":"Just another EDURES CMS QA Admin site Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ucf.edu\/research\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/www.ucf.edu\/research\/wp-json\/wp\/v2\/person\/238","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ucf.edu\/research\/wp-json\/wp\/v2\/person"}],"about":[{"href":"https:\/\/www.ucf.edu\/research\/wp-json\/wp\/v2\/types\/person"}],"version-history":[{"count":9,"href":"https:\/\/www.ucf.edu\/research\/wp-json\/wp\/v2\/person\/238\/revisions"}],"predecessor-version":[{"id":5738,"href":"https:\/\/www.ucf.edu\/research\/wp-json\/wp\/v2\/person\/238\/revisions\/5738"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ucf.edu\/research\/wp-json\/wp\/v2\/media\/4753"}],"wp:attachment":[{"href":"https:\/\/www.ucf.edu\/research\/wp-json\/wp\/v2\/media?parent=238"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ucf.edu\/research\/wp-json\/wp\/v2\/categories?post=238"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ucf.edu\/research\/wp-json\/wp\/v2\/tags?post=238"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}